{"id":21377,"date":"2026-04-22T08:29:25","date_gmt":"2026-04-22T06:29:25","guid":{"rendered":"https:\/\/astei.com\/?p=21377"},"modified":"2026-05-06T15:07:21","modified_gmt":"2026-05-06T13:07:21","slug":"non-jan-jatetxe-onenak","status":"publish","type":"post","link":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/","title":{"rendered":"Non jan: jatetxe onenak"},"content":{"rendered":"\n<p>En el Pa\u00eds Vasco vas a disfrutar de la gastronom\u00eda y el buen comer como en ning\u00fan otro lugar: pescados, carnes, verduras, hortalizas, vinos, quesos\u2026 Lo mejor del mar y de la tierra se re\u00fanen en un extraordinario men\u00fa de posibilidades sobre tu mesa.<\/p>\n\n<p>A continuaci\u00f3n te presentamos una lista con nuestros restaurantes favoritos de la zona.<\/p>\n\n<h3 class=\"wp-block-heading has-text-color\" style=\"color:#91c500\">Kanala Beach Jatetxea<\/h3>\n\n<p>En el comedor gastron\u00f3mico encontrar\u00e1s platos como anchoas del Golfo de Bizkaia, carnes premium (T-bone, pich\u00f3n), pescados frescos como bacalao al pil-pil o merluza con emulsi\u00f3n de erizo, y entrantes \u00fanicos como gazpacho de sand\u00eda o pulpo a la brasa Josper Kanala Beach.<\/p>\n\n<p>En la terraza, destaca su carta de arroces (solo viernes y s\u00e1bado por la noche), que incluye opciones como arroz de carabinero, melosos de rape, gambas rojas o rabo con piparras. Tambi\u00e9n ofrecen brasa, hamburguesas creativas como la \u201cKanala Burger\u201d (venado) o \u201cAngus Burger\u201d, y picoteo gourmet. Un lugar referente en la zona, combinando comida de calidad, servicio impecable y ambiente inmejorable.<\/p>\n\n<p><a href=\"https:\/\/www.kanalabeach.eus\/\">kanalabeach.eus<\/a><\/p>\n\n<h3 class=\"wp-block-heading has-text-color has-link-color wp-elements-83dc565983509067dd561bc2dbc6c8c5\" style=\"color:#91c500\">Atxarre Taberna<\/h3>\n\n<p>Ofrecen un servicio diario de elaboraci\u00f3n de pintxos de calidad y una carta variada de raciones y bocadillos desde un enclave natural extraordinario.<\/p>\n\n<p>Laida<br\/><a href=\"https:\/\/atxarre.net\/\" target=\"_blank\" rel=\"noreferrer noopener\">atxarre.net\/<\/a><\/p>\n\n<h3 class=\"wp-block-heading has-text-color\" style=\"color:#91c500\"><br\/>Arita-Berri<\/h3>\n\n<p>La propuesta culinaria combina la cocina vasca tradicional con toques de modernidad, basada en productos de alta calidad: pescado y marisco de la Costa Cant\u00e1brica, carnes procedentes de pastos locales y reposter\u00eda casera<\/p>\n\n<p><a href=\"http:\/\/www.aritaberri.com\" target=\"_blank\" rel=\"noreferrer noopener\">aritaberri.com<\/a><br\/>Barrio de Basetxetas-Atxoste, 23 48313 Ere\u00f1o,<br\/>Tel\u00e9fono:946 25 04 54<br\/>A 1 Km de las Casas de Ea Astei<\/p>\n\n<h3 class=\"wp-block-heading has-text-color\" style=\"color:#91c500\">Portuondo<\/h3>\n\n<p>Restaurante. Cocina vasca de calidad con unas vistas espectaculares del estuario.<br\/>Cervecera. La cervecera es un espacio moderno, con cocina al estilo de las cerveceras tradicionales. Se trata de un men\u00fa sencillo, pero en el que se cuida la calidad de la materia prima, as\u00ed como su elaboraci\u00f3n y presentaci\u00f3n.<\/p>\n\n<p>Entre Mundaka y Bermeo<br\/><a href=\"https:\/\/www.restauranteportuondo.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">restauranteportuondo.com\/<\/a><\/p>\n\n<h3 class=\"wp-block-heading has-text-color\" style=\"color:#91c500\"><br\/>Ermintxo<\/h3>\n\n<p>Una cocina vasca tradicional, con fuerte presencia de pescado y marisco fresco, tra\u00eddo directamente de puertos cercanos como Lekeitio, junto con carnes Euskolabel de alta calidad<\/p>\n\n<p><a href=\"https:\/\/www.hotelermintxo.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">hotelermintxo.com\/<br\/><\/a>Elejalde Auzoa, 30, 48311 Natxitua, Bizkaia<br\/>Tel\u00e9fono: 946 27 77 00A<br\/>1,5km de las Casas de Ea Astei<\/p>\n\n<h3 class=\"wp-block-heading has-text-color\" style=\"color:#91c500\"><br\/>Restaurante Madaoxagane (Busturia)<\/h3>\n\n<p>Este restaurante se enfoca en una cocina tradicional con un fuerte acento en el producto local y de temporada, bajo una filosof\u00eda de \u00abkil\u00f3metro cero\u00bb. Es un lugar ideal para familias, ya que cuenta con una amplia terraza, campas, columpios y un laberinto para los ni\u00f1os, lo que permite a los adultos disfrutar de una comida tranquila mientras los peque\u00f1os se divierten.<\/p>\n\n<p>Busturia<br\/><a href=\"http:\/\/www.restaurantemadaixagane.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.restaurantemadaixagane.es\/<\/a><\/p>\n\n<h3 class=\"wp-block-heading has-text-color\" style=\"color:#91c500\">Zallo Barri<\/h3>\n\n<p>Guiado actualmente por el chef Eneko Ordorika, Zallo-Barri ofrece una experiencia gastron\u00f3mica donde se combina tradici\u00f3n vasca, productos locales y propuestas de autor con un enfoque creativo<\/p>\n\n<p><a href=\"http:\/\/zallobarri.com\" target=\"_blank\" rel=\"noreferrer noopener\">www.zallobari.com<br\/><\/a>Juan Calzada Kalea, 79 48300 Gernika-Lumo, Bizkaia<br\/>Tel\u00e9fono: 946 25 18 00<br\/>Gernika, a unos 10 km de nuestras casas.<\/p>\n\n<h2 class=\"wp-block-heading has-text-color\" style=\"color:#91c500\">Restaurantes con Estrella Michelin<\/h2>\n\n<p><\/p>\n\n<p>\u00bfSab\u00edas que en el Pa\u00eds Vasco hay 24 restaurantes con m\u00e1s de una estrella Michelin. Hemos elegido para ti os tres m\u00e1s cercanos a las Casas Rurales de Ea Astei.<\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/etxabarri-1024x678.png\" alt=\"Las casas rurales de Ea Astei, parque natural de Urdaibai, Pa&#xED;s Vasco\" class=\"wp-image-4249\" srcset=\"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/etxabarri-1024x678.png 1024w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/etxabarri-600x397.png 600w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/etxabarri-300x199.png 300w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/etxabarri-768x508.png 768w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/etxabarri.png 1284w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><br\/>El m\u00e1s cercano a nuestras casas el el <strong>Asador Etxebarri<\/strong>, situado en San Juan Plaza 1, 48291 Atxondo, Bizkaia <\/p>\n\n<p><a href=\"http:\/\/asadoretxebarri.com\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/asadoretxebarri.com\/es\/<\/a><\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"455\" src=\"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/azurmendi-sustainable-restaurant-1024x455.png\" alt=\"Las casas rurales de Ea Astei, parque natural de Urdaibai, Pa&#xED;s Vasco\" class=\"wp-image-4247\" srcset=\"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/azurmendi-sustainable-restaurant-1024x455.png 1024w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/azurmendi-sustainable-restaurant-600x267.png 600w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/azurmendi-sustainable-restaurant-300x133.png 300w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/azurmendi-sustainable-restaurant-768x342.png 768w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/azurmendi-sustainable-restaurant-1536x683.png 1536w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/azurmendi-sustainable-restaurant.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p><a href=\"http:\/\/asadoretxebarri.com\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\"><br\/><\/a>El <strong>Restaurante Azurmendi,<\/strong> situado en el Barrio Legina de Larrabetzu, un precioso pueblo bizkaino, es uno de nuestros restaurantes m\u00e1s emblem\u00e1ticos y famosos a nivel internacional. COn un edificio preocupado por la sostenibilidad, sin duda te sorprender\u00e1.<\/p>\n\n<p><a href=\"https:\/\/azurmendi.restaurant\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/azurmendi.restaurant\/<br\/><\/a><\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"606\" src=\"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/zortziko-1024x606.png\" alt=\"Las casas rurales de Ea Astei, parque natural de Urdaibai, Pa&#xED;s Vasco\" class=\"wp-image-4243\" srcset=\"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/zortziko-1024x606.png 1024w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/zortziko-600x355.png 600w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/zortziko-300x177.png 300w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/zortziko-768x454.png 768w, https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/zortziko.png 1067w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Muy famoso es el restaurante <strong>Zortziko<\/strong>, en Bilbao, muy cerca del museo Guggenheim.<\/p>\n\n<p><a href=\"https:\/\/www.zortziko.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">  https:\/\/www.zortziko.es\/<\/a><\/p>\n\n<p>SI vas a pasar unos d\u00edas en el entorno de Urdaibai ir\u00e1s descubriendo nuevos lugares donde comer. Casi en cualquier tasca, taberna y bar en el Pa\u00eds Vasco cuata con su peque\u00f1a tradici\u00f3n culinaria, basada en productos de km. 0 y de temporada. Os vais a volver locos  con sus pintxos, gildas y peque\u00f1as delicatessen. <\/p>\n\n<p>\u00a1Ay! \u00bfCu\u00e1l me como ahora?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Itsasoaren eta lurraren onenak elkartzen dira aukera-menu paregabe batean, eta hori bete-betean gozatu ahal izango duzu.<\/p>\n","protected":false},"author":18,"featured_media":4240,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[275,274],"tags":[],"class_list":["post-21377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-egin-beharrekoa","category-ingurumena"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Non jan: jatetxe onenak - Las Casas de Ea Astei<\/title>\n<meta name=\"description\" content=\"Gastronomia gustuko baduzu, ezagutu Bizkaian, EAEn, ondo jan dezakezun gure jatetxe gogokoenak.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Non jan: jatetxe onenak - Las Casas de Ea Astei\" \/>\n<meta property=\"og:description\" content=\"Gastronomia gustuko baduzu, ezagutu Bizkaian, EAEn, ondo jan dezakezun gure jatetxe gogokoenak.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/\" \/>\n<meta property=\"og:site_name\" content=\"Las Casas de Ea Astei\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EAASTEI\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-22T06:29:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T13:07:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/pintxos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"933\" \/>\n\t<meta property=\"og:image:height\" content=\"584\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jose Gutierrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/\"},\"author\":{\"name\":\"Jose Gutierrez\",\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/#\\\/schema\\\/person\\\/e042e3af2af13cf7d664244423ddf40e\"},\"headline\":\"Non jan: jatetxe onenak\",\"datePublished\":\"2026-04-22T06:29:25+00:00\",\"dateModified\":\"2026-05-06T13:07:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/\"},\"wordCount\":672,\"publisher\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astei.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/pintxos.png\",\"articleSection\":[\"Egin beharrekoa\",\"Ingurumena\"],\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/\",\"url\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/\",\"name\":\"Non jan: jatetxe onenak - Las Casas de Ea Astei\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astei.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/pintxos.png\",\"datePublished\":\"2026-04-22T06:29:25+00:00\",\"dateModified\":\"2026-05-06T13:07:21+00:00\",\"description\":\"Gastronomia gustuko baduzu, ezagutu Bizkaian, EAEn, ondo jan dezakezun gure jatetxe gogokoenak.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astei.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/pintxos.png\",\"contentUrl\":\"https:\\\/\\\/astei.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/pintxos.png\",\"width\":933,\"height\":584,\"caption\":\"Las casas rurales de Ea Astei, parque natural de Urdaibai, Pa\u00eds Vasco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/blog\\\/non-jan-jatetxe-onenak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Cover\",\"item\":\"https:\\\/\\\/astei.com\\\/eu\\\/hasiera\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non jan: jatetxe onenak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/astei.com\\\/eu\\\/\",\"name\":\"Las Casas de Ea Astei\",\"description\":\"Tus alojamientos rurales perfectos en el para\u00edso de Urdaibai\",\"publisher\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/#organization\"},\"alternateName\":\"Tourist accommodations in Basque Country\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astei.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/#organization\",\"name\":\"The Houses of Ea Astei\",\"alternateName\":\"Tourist accommodations in Basque Country\",\"url\":\"https:\\\/\\\/astei.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/astei.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-Astei-Negro.png?fit=164%2C108&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/astei.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-Astei-Negro.png?fit=164%2C108&ssl=1\",\"width\":164,\"height\":108,\"caption\":\"The Houses of Ea Astei\"},\"image\":{\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EAASTEI\",\"https:\\\/\\\/www.instagram.com\\\/eaastei\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ea-astei-casa-rural-74004636\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astei.com\\\/eu\\\/#\\\/schema\\\/person\\\/e042e3af2af13cf7d664244423ddf40e\",\"name\":\"Jose Gutierrez\",\"sameAs\":[\"https:\\\/\\\/digixop.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Non jan: jatetxe onenak - Las Casas de Ea Astei","description":"Gastronomia gustuko baduzu, ezagutu Bizkaian, EAEn, ondo jan dezakezun gure jatetxe gogokoenak.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/","og_locale":"eu_ES","og_type":"article","og_title":"Non jan: jatetxe onenak - Las Casas de Ea Astei","og_description":"Gastronomia gustuko baduzu, ezagutu Bizkaian, EAEn, ondo jan dezakezun gure jatetxe gogokoenak.","og_url":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/","og_site_name":"Las Casas de Ea Astei","article_publisher":"https:\/\/www.facebook.com\/EAASTEI","article_published_time":"2026-04-22T06:29:25+00:00","article_modified_time":"2026-05-06T13:07:21+00:00","og_image":[{"width":933,"height":584,"url":"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/pintxos.png","type":"image\/png"}],"author":"Jose Gutierrez","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/#article","isPartOf":{"@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/"},"author":{"name":"Jose Gutierrez","@id":"https:\/\/astei.com\/eu\/#\/schema\/person\/e042e3af2af13cf7d664244423ddf40e"},"headline":"Non jan: jatetxe onenak","datePublished":"2026-04-22T06:29:25+00:00","dateModified":"2026-05-06T13:07:21+00:00","mainEntityOfPage":{"@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/"},"wordCount":672,"publisher":{"@id":"https:\/\/astei.com\/eu\/#organization"},"image":{"@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/#primaryimage"},"thumbnailUrl":"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/pintxos.png","articleSection":["Egin beharrekoa","Ingurumena"],"inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/","url":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/","name":"Non jan: jatetxe onenak - Las Casas de Ea Astei","isPartOf":{"@id":"https:\/\/astei.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/#primaryimage"},"image":{"@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/#primaryimage"},"thumbnailUrl":"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/pintxos.png","datePublished":"2026-04-22T06:29:25+00:00","dateModified":"2026-05-06T13:07:21+00:00","description":"Gastronomia gustuko baduzu, ezagutu Bizkaian, EAEn, ondo jan dezakezun gure jatetxe gogokoenak.","breadcrumb":{"@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/#primaryimage","url":"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/pintxos.png","contentUrl":"https:\/\/astei.com\/wp-content\/uploads\/2020\/10\/pintxos.png","width":933,"height":584,"caption":"Las casas rurales de Ea Astei, parque natural de Urdaibai, Pa\u00eds Vasco"},{"@type":"BreadcrumbList","@id":"https:\/\/astei.com\/eu\/blog\/non-jan-jatetxe-onenak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Cover","item":"https:\/\/astei.com\/eu\/hasiera\/"},{"@type":"ListItem","position":2,"name":"Non jan: jatetxe onenak"}]},{"@type":"WebSite","@id":"https:\/\/astei.com\/eu\/#website","url":"https:\/\/astei.com\/eu\/","name":"Las Casas de Ea Astei","description":"Tus alojamientos rurales perfectos en el para\u00edso de Urdaibai","publisher":{"@id":"https:\/\/astei.com\/eu\/#organization"},"alternateName":"Tourist accommodations in Basque Country","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astei.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/astei.com\/eu\/#organization","name":"The Houses of Ea Astei","alternateName":"Tourist accommodations in Basque Country","url":"https:\/\/astei.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/astei.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/astei.com\/wp-content\/uploads\/2019\/02\/Logo-Astei-Negro.png?fit=164%2C108&ssl=1","contentUrl":"https:\/\/i0.wp.com\/astei.com\/wp-content\/uploads\/2019\/02\/Logo-Astei-Negro.png?fit=164%2C108&ssl=1","width":164,"height":108,"caption":"The Houses of Ea Astei"},"image":{"@id":"https:\/\/astei.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EAASTEI","https:\/\/www.instagram.com\/eaastei\/","https:\/\/www.linkedin.com\/in\/ea-astei-casa-rural-74004636\/"]},{"@type":"Person","@id":"https:\/\/astei.com\/eu\/#\/schema\/person\/e042e3af2af13cf7d664244423ddf40e","name":"Jose Gutierrez","sameAs":["https:\/\/digixop.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/posts\/21377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/comments?post=21377"}],"version-history":[{"count":2,"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/posts\/21377\/revisions"}],"predecessor-version":[{"id":22395,"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/posts\/21377\/revisions\/22395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/media\/4240"}],"wp:attachment":[{"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/media?parent=21377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/categories?post=21377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astei.com\/eu\/wp-json\/wp\/v2\/tags?post=21377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}