{"id":757,"date":"2015-04-14T11:49:00","date_gmt":"2015-04-14T09:49:00","guid":{"rendered":"https:\/\/astei.com\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/"},"modified":"2021-04-14T15:46:11","modified_gmt":"2021-04-14T13:46:11","slug":"3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe","status":"publish","type":"post","link":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/","title":{"rendered":"3 razones de peso para visitar San Juan de Gaztelugatxe"},"content":{"rendered":"<div>\n<p>1.-\u00danico<\/p>\n<p>Este emblema costero de\u00a0<a title=\"Los 4 pueblos de Vizcaya con m\u00e1s encanto\" href=\"http:\/\/turismovasco.com\/vizcaya\/que-ver-vizcaya\/4-pueblos-vizcaya-encanto\/\">Vizcaya<\/a>\u00a0es \u00fanico, no solo en el pa\u00eds vasco sino en todo el mundo. \u00danico por su ubicaci\u00f3n en un mar que en invierno es temible hasta por hombres que lo surcan cientos de veces al a\u00f1o, \u00fanico por sus 231 pelda\u00f1os o escalones, \u00fanico por su ermita de la que se desconoce a\u00f1o de construcci\u00f3n, quieres m\u00e1s?<\/p>\n<p><iframe style=\"border-style: none; border-width: 0px; box-sizing: border-box; left: 0px; list-style: none; margin: 0px; max-width: 100%; outline: none; padding: 0px; position: absolute; top: 0px;\" name=\"aswift_0\" width=\"620\" height=\"60\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe>2.-Tradici\u00f3n<\/p>\n<p>La ermita de San Juan de Gaztelugatxe es tradici\u00f3n, tradici\u00f3n para el pueblo vasco, y m\u00e1s aun si cabe para el pueblo de Bermeo, en el cual esta ubicada esta obra de arte de la naturaleza y del hombre. Los pescadores Bermeanos la utilizaban y utilizan (hoy en d\u00eda en menos ocasiones) como sitio de ofrecer ofrendas para sus viajes por el mar.<\/p>\n<p>3.-Belleza<\/p>\n<p>No es casualidad que muchos famosos vascos la usen como lugar donde celebrar su boda, ejemplo de ello podemos citar a la famosa presentadora de televisi\u00f3n Ane Igarteburu, esto se debe a su belleza. Uno de los pocos sitios donde te sientes que el suelo que pisas pertenece al mar, una mezcla de mar y roca que sin dudar a dudas merece ser visitado.<\/p>\n<p>http:\/\/turismovasco.com\/vizcaya\/que-ver-vizcaya\/razones-visitar-san-juan-de-gaztelugatxe\/<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>3 razones -y muchas m\u00e1s que descubrir\u00e1s en persona- para visitar San Juan de Gaztelugatxe \u00bfSab\u00edas que aqu\u00ed se rod\u00f3 una de las temporadas de la famosa serie &#8222;Juego de Tronos&#8220;?<\/p>\n","protected":false},"author":18,"featured_media":660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[28],"tags":[37,133,35,34,33,132,22],"class_list":["post-757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entorno","tag-fotografia","tag-juego-de-tronos","tag-naturaleza","tag-pais-vasco","tag-que-hacer","tag-san-juan-de-gaztelugatxe","tag-turismo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 razones de peso para visitar San Juan de Gaztelugatxe - Las Casas de Ea Astei<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 razones de peso para visitar San Juan de Gaztelugatxe - Las Casas de Ea Astei\" \/>\n<meta property=\"og:description\" content=\"3 razones -y muchas m\u00e1s que descubrir\u00e1s en persona- para visitar San Juan de Gaztelugatxe \u00bfSab\u00edas que aqu\u00ed se rod\u00f3 una de las temporadas de la famosa serie &quot;Juego de Tronos&quot;?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/\" \/>\n<meta property=\"og:site_name\" content=\"Las Casas de Ea Astei\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EAASTEI\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-14T09:49:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-14T13:46:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/astei.com\/wp-content\/uploads\/2015\/04\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg?fit=1024%2C682&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jose Gutierrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/\"},\"author\":{\"name\":\"Jose Gutierrez\",\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/#\\\/schema\\\/person\\\/e042e3af2af13cf7d664244423ddf40e\"},\"headline\":\"3 razones de peso para visitar San Juan de Gaztelugatxe\",\"datePublished\":\"2015-04-14T09:49:00+00:00\",\"dateModified\":\"2021-04-14T13:46:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/\"},\"wordCount\":220,\"publisher\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astei.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg\",\"keywords\":[\"fotograf\u00eda\",\"juego de tronos\",\"naturaleza\",\"pa\u00eds vasco\",\"qu\u00e9 hacer\",\"san juan de gaztelugatxe\",\"turismo\"],\"articleSection\":[\"El entorno\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/\",\"url\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/\",\"name\":\"3 razones de peso para visitar San Juan de Gaztelugatxe - Las Casas de Ea Astei\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astei.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg\",\"datePublished\":\"2015-04-14T09:49:00+00:00\",\"dateModified\":\"2021-04-14T13:46:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astei.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg\",\"contentUrl\":\"https:\\\/\\\/astei.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg\",\"width\":1024,\"height\":682,\"caption\":\"San Juan de Gaztelugatxe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/blog\\\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Cover\",\"item\":\"https:\\\/\\\/astei.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 razones de peso para visitar San Juan de Gaztelugatxe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/astei.com\\\/de\\\/\",\"name\":\"Las Casas de Ea Astei\",\"description\":\"Tus alojamientos rurales perfectos en el para\u00edso de Urdaibai\",\"publisher\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/#organization\"},\"alternateName\":\"Tourist accommodations in Basque Country\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astei.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/#organization\",\"name\":\"The Houses of Ea Astei\",\"alternateName\":\"Tourist accommodations in Basque Country\",\"url\":\"https:\\\/\\\/astei.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/astei.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-Astei-Negro.png?fit=164%2C108&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/astei.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Logo-Astei-Negro.png?fit=164%2C108&ssl=1\",\"width\":164,\"height\":108,\"caption\":\"The Houses of Ea Astei\"},\"image\":{\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EAASTEI\",\"https:\\\/\\\/www.instagram.com\\\/eaastei\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ea-astei-casa-rural-74004636\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/astei.com\\\/de\\\/#\\\/schema\\\/person\\\/e042e3af2af13cf7d664244423ddf40e\",\"name\":\"Jose Gutierrez\",\"sameAs\":[\"https:\\\/\\\/digixop.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 razones de peso para visitar San Juan de Gaztelugatxe - Las Casas de Ea Astei","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/","og_locale":"de_DE","og_type":"article","og_title":"3 razones de peso para visitar San Juan de Gaztelugatxe - Las Casas de Ea Astei","og_description":"3 razones -y muchas m\u00e1s que descubrir\u00e1s en persona- para visitar San Juan de Gaztelugatxe \u00bfSab\u00edas que aqu\u00ed se rod\u00f3 una de las temporadas de la famosa serie \"Juego de Tronos\"?","og_url":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/","og_site_name":"Las Casas de Ea Astei","article_publisher":"https:\/\/www.facebook.com\/EAASTEI","article_published_time":"2015-04-14T09:49:00+00:00","article_modified_time":"2021-04-14T13:46:11+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/i0.wp.com\/astei.com\/wp-content\/uploads\/2015\/04\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg?fit=1024%2C682&ssl=1","type":"image\/jpeg"}],"author":"Jose Gutierrez","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/#article","isPartOf":{"@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/"},"author":{"name":"Jose Gutierrez","@id":"https:\/\/astei.com\/de\/#\/schema\/person\/e042e3af2af13cf7d664244423ddf40e"},"headline":"3 razones de peso para visitar San Juan de Gaztelugatxe","datePublished":"2015-04-14T09:49:00+00:00","dateModified":"2021-04-14T13:46:11+00:00","mainEntityOfPage":{"@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/"},"wordCount":220,"publisher":{"@id":"https:\/\/astei.com\/de\/#organization"},"image":{"@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/#primaryimage"},"thumbnailUrl":"https:\/\/astei.com\/wp-content\/uploads\/2015\/04\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg","keywords":["fotograf\u00eda","juego de tronos","naturaleza","pa\u00eds vasco","qu\u00e9 hacer","san juan de gaztelugatxe","turismo"],"articleSection":["El entorno"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/","url":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/","name":"3 razones de peso para visitar San Juan de Gaztelugatxe - Las Casas de Ea Astei","isPartOf":{"@id":"https:\/\/astei.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/#primaryimage"},"image":{"@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/#primaryimage"},"thumbnailUrl":"https:\/\/astei.com\/wp-content\/uploads\/2015\/04\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg","datePublished":"2015-04-14T09:49:00+00:00","dateModified":"2021-04-14T13:46:11+00:00","breadcrumb":{"@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/#primaryimage","url":"https:\/\/astei.com\/wp-content\/uploads\/2015\/04\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg","contentUrl":"https:\/\/astei.com\/wp-content\/uploads\/2015\/04\/AM-OpJALAzPzOPEIY1aMHYrBM3pPGXccWFH-ITEVtg0.jpg","width":1024,"height":682,"caption":"San Juan de Gaztelugatxe"},{"@type":"BreadcrumbList","@id":"https:\/\/astei.com\/de\/blog\/3-razones-de-peso-para-visitar-san-juan-de-gaztelugatxe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Cover","item":"https:\/\/astei.com\/de\/"},{"@type":"ListItem","position":2,"name":"3 razones de peso para visitar San Juan de Gaztelugatxe"}]},{"@type":"WebSite","@id":"https:\/\/astei.com\/de\/#website","url":"https:\/\/astei.com\/de\/","name":"Las Casas de Ea Astei","description":"Tus alojamientos rurales perfectos en el para\u00edso de Urdaibai","publisher":{"@id":"https:\/\/astei.com\/de\/#organization"},"alternateName":"Tourist accommodations in Basque Country","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astei.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/astei.com\/de\/#organization","name":"The Houses of Ea Astei","alternateName":"Tourist accommodations in Basque Country","url":"https:\/\/astei.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/astei.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/astei.com\/wp-content\/uploads\/2019\/02\/Logo-Astei-Negro.png?fit=164%2C108&ssl=1","contentUrl":"https:\/\/i0.wp.com\/astei.com\/wp-content\/uploads\/2019\/02\/Logo-Astei-Negro.png?fit=164%2C108&ssl=1","width":164,"height":108,"caption":"The Houses of Ea Astei"},"image":{"@id":"https:\/\/astei.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EAASTEI","https:\/\/www.instagram.com\/eaastei\/","https:\/\/www.linkedin.com\/in\/ea-astei-casa-rural-74004636\/"]},{"@type":"Person","@id":"https:\/\/astei.com\/de\/#\/schema\/person\/e042e3af2af13cf7d664244423ddf40e","name":"Jose Gutierrez","sameAs":["https:\/\/digixop.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/posts\/757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/comments?post=757"}],"version-history":[{"count":0,"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/posts\/757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/media\/660"}],"wp:attachment":[{"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/media?parent=757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/categories?post=757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/astei.com\/de\/wp-json\/wp\/v2\/tags?post=757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}